{"id":3295,"date":"2022-04-04T23:46:28","date_gmt":"2022-04-04T21:46:28","guid":{"rendered":"https:\/\/jarnac-champagne.fr\/\/\/?p=3295"},"modified":"2022-04-05T07:23:32","modified_gmt":"2022-04-05T05:23:32","slug":"presentation-et-lancement-de-lheure-civique","status":"publish","type":"post","link":"https:\/\/jarnac-champagne.fr\/index.php\/2022\/04\/04\/presentation-et-lancement-de-lheure-civique\/","title":{"rendered":"Pr\u00e9sentation et lancement de l&rsquo;heure civique"},"content":{"rendered":"\n<p>Vendredi 01 avril, a eu lieu la pr\u00e9sentation et le lancement officiel de l&rsquo;heure civique jarnacaise. en pr\u00e9sence d&rsquo;Atanase P\u00e9rifan (cr\u00e9ateur de la F\u00eate des Voisins), de Mme Guimberteau (Conseill\u00e8re D\u00e9partementales), de quelques \u00e9lus, et d&rsquo;administr\u00e9s qui \u0153uvrent d\u00e9j\u00e0 en ce sens de mani\u00e8re spontan\u00e9e.<\/p>\n\n\n\n<p>C&rsquo;est autour d&rsquo;un caf\u00e9 et de quelques douceurs pr\u00e9par\u00e9es par Nadine que s&rsquo;est achev\u00e9 ce petit moment sympathique.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color\"><strong>L&rsquo;heure civique, qu&rsquo;est-ce que c&rsquo;est ?<\/strong> Chacun de nous peut le faire ! Les champs d&rsquo;action sont multiples  (aide aux devoirs, faire des courses, tenir compagnie, apprendre Internet, aide au bricolage). Plus largement, participer \u00e0 une actions citoyenne telle que le d\u00e9sherbage du centre bourg, le ramassage des d\u00e9chets.<\/p>\n\n\n\n<p>Plus que jamais, en cette p\u00e9riode compliqu\u00e9e, nous devons faire preuve d&rsquo;entraide, de solidarit\u00e9. C&rsquo;est ensemble que nous pouvons recr\u00e9er du lien.<\/p>\n\n\n\n<p>Nous comptons sur vous !<\/p>\n\n\n\n<p class=\"has-luminous-vivid-orange-color has-text-color\"><strong>Vous souhaitez vous inscrire pour proposer votre aide ponctuelle \u00e0 qui en aurait besoin, c&rsquo;est ici : <a href=\"https:\/\/jarnac-champagne.lheurecivique.fr\/\">https:\/\/jarnac-champagne.lheurecivique.fr\/<\/a> ou bien fa\u00eetes-vous conna\u00eetre \u00e0 la Mairie, nous nous chargerons de votre inscription.<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color\"><strong>Vous avez besoin d&rsquo;aide, contactez-nous par mail mairie-jarnac-champagne@wanadoo.fr ou par t\u00e9l\u00e9phone au 05 46 49 50 71, quelqu\u2019un pourra peut-\u00eatre r\u00e9pondre \u00e0 votre demande.<\/strong><\/p>\n\n\n\n<p>Plus d&rsquo;informations sur : <a href=\"https:\/\/lheurecivique.charente-maritime.fr\/\">https:\/\/lheurecivique.charente-maritime.fr\/<\/a><\/p>\n\n\n<a href=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Tract-HC-Jarnac-1.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Tract-HC-Jarnac-1<\/a>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n\n\n<a href=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Tract-HC-Jarnac-2.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Tract-HC-Jarnac-2<\/a>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"996\" data-id=\"3303\" src=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-1024x996.jpg\" alt=\"\" class=\"wp-image-3303\" srcset=\"https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-1024x996.jpg 1024w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-300x292.jpg 300w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-768x747.jpg 768w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-1536x1495.jpg 1536w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-220-2-2048x1993.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"706\" height=\"1024\" data-id=\"3307\" src=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-706x1024.jpg\" alt=\"\" class=\"wp-image-3307\" srcset=\"https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-706x1024.jpg 706w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-207x300.jpg 207w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-768x1114.jpg 768w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-1059x1536.jpg 1059w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-1412x2048.jpg 1412w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-221-2-scaled.jpg 1766w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"874\" data-id=\"3302\" src=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-1024x874.jpg\" alt=\"\" class=\"wp-image-3302\" srcset=\"https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-1024x874.jpg 1024w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-300x256.jpg 300w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-768x655.jpg 768w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-1536x1310.jpg 1536w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-222-2-2048x1747.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"3304\" src=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-1024x681.jpg\" alt=\"\" class=\"wp-image-3304\" srcset=\"https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-1024x681.jpg 1024w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-300x200.jpg 300w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-768x511.jpg 768w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-1536x1022.jpg 1536w, https:\/\/jarnac-champagne.fr\/wp-content\/uploads\/2022\/04\/Heure_Civique_01-04-223-2-2048x1363.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>SONY DSC<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vendredi 01 avril, a eu lieu la pr\u00e9sentation et le lancement officiel de l&rsquo;heure civique jarnacaise. en pr\u00e9sence d&rsquo;Atanase P\u00e9rifan<\/p>\n","protected":false},"author":1,"featured_media":105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[],"class_list":["post-3295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-mairie"],"_links":{"self":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/3295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3295"}],"version-history":[{"count":6,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/3295\/revisions"}],"predecessor-version":[{"id":3315,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/3295\/revisions\/3315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media\/105"}],"wp:attachment":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}