{"id":4799,"date":"2023-06-24T17:29:43","date_gmt":"2023-06-24T15:29:43","guid":{"rendered":"https:\/\/jarnac-champagne.fr\/\/\/?p=4799"},"modified":"2023-06-24T17:29:44","modified_gmt":"2023-06-24T15:29:44","slug":"feux-de-recoltes-un-risque-bien-reel","status":"publish","type":"post","link":"https:\/\/jarnac-champagne.fr\/index.php\/2023\/06\/24\/feux-de-recoltes-un-risque-bien-reel\/","title":{"rendered":"Feux de r\u00e9coltes\u00a0: un risque bien r\u00e9el"},"content":{"rendered":"\n<p><em>Chaque ann\u00e9e, les sapeurs-pompiers sont fortement mobilis\u00e9s pour lutter contre les feux d\u2019espaces naturels. Si les feux de for\u00eat sont majoritaires, les feux de r\u00e9coltes existent aussi. En Charente-Maritime, ils ont repr\u00e9sent\u00e9 une centaine d\u2019interventions en 2022.<\/em><\/p>\n\n\n\n<p>Il suffit parfois de pas grand-chose&nbsp;: des poussi\u00e8res qui s&rsquo;enflamment dans un engin agricole, des courroies qui s&rsquo;\u00e9chauffent, des roulements coinc\u00e9s, un pot d&rsquo;\u00e9chappement br\u00fblant, un m\u00e9got jet\u00e9 depuis la route &#8230; et le feu d\u00e9marre. C&rsquo;est d&rsquo;autant plus dangereux lorsque les sols sont secs, les temp\u00e9ratures \u00e9lev\u00e9es et le vent violent.<\/p>\n\n\n\n<p><a><\/a> La pr\u00e9vention de ces incendies d\u00e9marre en amont des moissons rappellent les sapeurs-pompiers. En effet, un bon entretien des machines agricoles (graissage des m\u00e9canismes, recherches de fuite) et un d\u00e9poussi\u00e9rage r\u00e9gulier permettent d\u2019\u00e9viter les points chauds.<\/p>\n\n\n\n<p>Le risque incendie peut aussi se r\u00e9duire lors de la moisson. D\u2019une part, en choisissant de moissonner le matin ou en soir\u00e9e, lorsque les temp\u00e9ratures sont moins \u00e9lev\u00e9es. Et d\u2019autre part, en d\u00e9butant la moisson par le milieu du champ afin de cr\u00e9er un coupe-feu&nbsp;; puis r\u00e9aliser le pourtour du champ pour \u00e9viter la propagation d\u2019un feu \u00e9ventuel \u00e0 la v\u00e9g\u00e9tation voisine. Il est recommand\u00e9 de moissonner face au vent pour que le feu s\u2019\u00e9tende vers une surface d\u00e9j\u00e0 moissonn\u00e9e.<\/p>\n\n\n\n<p>Enfin, si malgr\u00e9 les pr\u00e9cautions un incendie se d\u00e9clare, les r\u00e9flexes doivent \u00eatre identiques \u00e0 n\u2019importe quel feu. Essayer de traiter l\u2019incendie, sans se mettre en danger, avec un extincteur adapt\u00e9. Appeler le 18 ou le 112 et indiquer \u00e0 l\u2019op\u00e9rateur la localisation pr\u00e9cise, la nature de la r\u00e9colte, la surface du champ et la surface br\u00fbl\u00e9e. Se mettre en s\u00e9curit\u00e9. Et attendre les secours dans un endroit facilement visible.<\/p>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video height=\"1080\" style=\"aspect-ratio: 1080 \/ 1080;\" width=\"1080\" controls src=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2023\/06\/FEU-DE-RE\u2560uCOLTE-COMPLET_ss-titre-1.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, les sapeurs-pompiers sont fortement mobilis\u00e9s pour lutter contre les feux d\u2019espaces naturels. Si les feux de for\u00eat sont<\/p>\n","protected":false},"author":1,"featured_media":105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[],"class_list":["post-4799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-mairie"],"_links":{"self":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/4799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4799"}],"version-history":[{"count":1,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/4799\/revisions"}],"predecessor-version":[{"id":4802,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/4799\/revisions\/4802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media\/105"}],"wp:attachment":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}