{"id":5288,"date":"2023-10-30T19:02:31","date_gmt":"2023-10-30T18:02:31","guid":{"rendered":"https:\/\/jarnac-champagne.fr\/?p=5288"},"modified":"2023-10-30T19:02:33","modified_gmt":"2023-10-30T18:02:33","slug":"travaux-centre-des-finances-jonzac","status":"publish","type":"post","link":"https:\/\/jarnac-champagne.fr\/index.php\/2023\/10\/30\/travaux-centre-des-finances-jonzac\/","title":{"rendered":"Travaux centre des finances Jonzac"},"content":{"rendered":"\n<p>Le centre des finances publique de Jonzac fera l&rsquo;objet de travaux pendant une dur\u00e9e de 4 mois (ach\u00e8vement avant la campagne imp\u00f4ts sur le revenu). Ces travaux visent \u00e0 refaire l&rsquo;accueil des usagers et \u00e0 r\u00e9organiser les locaux occup\u00e9s par le SCG.<br><br>Ils d\u00e9buteront probablement d\u00e8s le<strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\"> 20 novembre 2023.<\/mark><\/strong><br><br><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-pink-color\">Pendant cette p\u00e9riode le public (renseignement et paiement) sera essentiellement accueilli dans un ALGECO install\u00e9 sur le parking<\/mark><\/strong>. L&rsquo;accueil du Centre d&rsquo;information et d&rsquo;orientation de l&rsquo;\u00e9ducation nationale restera inchang\u00e9 et le dispositif d&rsquo;accueil sur rendez-vous demeure.<br><br>Les service du SGC seront en partie relog\u00e9 dans l&rsquo;ALGECO \u00ab\u00a0service recette\u00a0\u00bb et en partie au 2\u00e8me \u00e9tage du b\u00e2timent \u00ab\u00a0service d\u00e9pense\u00a0\u00bb.<br><br>P\u00e9riode de mise en place du chantier :<br>&#8211; il n&rsquo;y aura <strong>pas de parking accessible aux usagers<\/strong> <strong>entre le 3 et le 8 novembre<\/strong> (installation des infrastructures du chantier)<br>&#8211; il n&rsquo;y aura <strong>pas d&rsquo;accueil du public du 15 au 17 novembre<\/strong> p\u00e9riode du d\u00e9m\u00e9nagement (les arr\u00eat\u00e9s pr\u00e9fectoraux ont \u00e9t\u00e9 pris)<br><br><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">P\u00e9riode des travaux (\u00e0 compter du 20 novembre)<br>&#8211; les places de stationnement seront fortement r\u00e9duites (emprise de l&rsquo;ALGECO),<br>&#8211; la zone d&rsquo;accueil abrit\u00e9e dans l&rsquo;ALGECO sera tr\u00e8s r\u00e9duite, en cas d&rsquo;affluence les usagers devront attendre dehors.<\/mark><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le centre des finances publique de Jonzac fera l&rsquo;objet de travaux pendant une dur\u00e9e de 4 mois (ach\u00e8vement avant la<\/p>\n","protected":false},"author":1,"featured_media":105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[],"class_list":["post-5288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-mairie"],"_links":{"self":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/5288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5288"}],"version-history":[{"count":2,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/5288\/revisions"}],"predecessor-version":[{"id":5290,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/5288\/revisions\/5290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media\/105"}],"wp:attachment":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}