{"id":7176,"date":"2025-05-25T20:12:54","date_gmt":"2025-05-25T18:12:54","guid":{"rendered":"https:\/\/jarnac-champagne.fr\/?p=7176"},"modified":"2025-05-25T20:12:55","modified_gmt":"2025-05-25T18:12:55","slug":"inscriptions-scolaires-2","status":"publish","type":"post","link":"https:\/\/jarnac-champagne.fr\/index.php\/2025\/05\/25\/inscriptions-scolaires-2\/","title":{"rendered":"Inscriptions scolaires"},"content":{"rendered":"\n<p>Nous en profitons pour vous rappeler l&rsquo;obligation de nous remettre un dossier d&rsquo;inscription COMPLET pour que votre enfant puisse b\u00e9n\u00e9ficier de la restauration scolaire. Merci de le rapporter en Mairie ou le confier \u00e0 l&rsquo;enseignant dans les meilleurs d\u00e9lais.<\/p>\n\n\n\n<p>Tout dossier incomplet vous sera retourn\u00e9. Merci pour votre compr\u00e9hension et votre collaboration.<\/p>\n\n\n<a href=\"https:\/\/jarnac-champagne.fr\/\/\/wp-content\/uploads\/2025\/05\/affiche-inscription.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">affiche-inscription<\/a>","protected":false},"excerpt":{"rendered":"<p>Nous en profitons pour vous rappeler l&rsquo;obligation de nous remettre un dossier d&rsquo;inscription COMPLET pour que votre enfant puisse b\u00e9n\u00e9ficier<\/p>\n","protected":false},"author":1,"featured_media":103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[],"class_list":["post-7176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-ecole"],"_links":{"self":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/7176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7176"}],"version-history":[{"count":2,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/7176\/revisions"}],"predecessor-version":[{"id":7179,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/posts\/7176\/revisions\/7179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media\/103"}],"wp:attachment":[{"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jarnac-champagne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}